{"id":18363,"date":"2023-10-02T09:40:33","date_gmt":"2023-10-02T13:40:33","guid":{"rendered":"https:\/\/chichi-curacao.com\/?p=18363"},"modified":"2023-10-02T15:12:16","modified_gmt":"2023-10-02T19:12:16","slug":"roadshow-germany","status":"publish","type":"post","link":"https:\/\/chichi-curacao.com\/nl\/2023\/10\/02\/roadshow-germany\/","title":{"rendered":"Cura\u00e7ao Roadshow Duitsland"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; module_id=&#8221;row-news&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#ff0098&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,2_3&#8243; admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;\/wp-content\/uploads\/sites\/15\/2016\/01\/chichi.png&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; module_id=&#8221;chichi-header-logo&#8221; _builder_version=&#8221;4.16&#8243; animation=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_id=&#8221;chichi-header-image&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; text_orientation=&#8221;right&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<a href=\"\/wp-content\/uploads\/sites\/15\/2016\/01\/news-1.png\" data-rel=\"lightbox-gallery-7PQUHQNM\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-974\" src=\"\/wp-content\/uploads\/sites\/15\/2016\/01\/news-1.png\" alt=\"news\" width=\"695\" height=\"135\" srcset=\"https:\/\/chichi-curacao.com\/wp-content\/uploads\/sites\/15\/2016\/01\/news-1.png 695w, https:\/\/chichi-curacao.com\/wp-content\/uploads\/sites\/15\/2016\/01\/news-1-300x58.png 300w\" sizes=\"(max-width: 695px) 100vw, 695px\" \/><\/a><br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;section&#8221; module_id=&#8221;bolletjes&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#ffffff&#8221; custom_padding_tablet=&#8221;50px|0|50px|0&#8243; custom_padding_phone=&#8221;&#8221; transparent_background=&#8221;off&#8221; padding_mobile=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_post_title author=&#8221;off&#8221; categories=&#8221;off&#8221; comments=&#8221;off&#8221; featured_image=&#8221;off&#8221; admin_label=&#8221;niet aanpassen&#8221; _builder_version=&#8221;4.16&#8243; title_all_caps=&#8221;off&#8221; background_color=&#8221;rgba(255,255,255,0)&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; parallax_effect=&#8221;on&#8221; module_bg_color=&#8221;rgba(255,255,255,0)&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_title][et_pb_text admin_label=&#8221;Hier tekst invoeren&#8221; module_id=&#8221;news-tekst&#8221; _builder_version=&#8221;4.22.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; z_index_tablet=&#8221;500&#8243; text_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_text_shadow_blur_strength_tablet=&#8221;1px&#8221; link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_2_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_2_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_2_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_3_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_3_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_3_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_4_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_4_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_4_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_5_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_5_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_5_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_6_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_6_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_6_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; use_border_color=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>CTBE (Cura\u00e7ao Tourist Board Europe) en KLM Duitsland bundelden hun krachten om een creatieve Cura\u00e7ao Roadshow in Duitsland te organiseren, een uniek evenement gericht op het vergroten van het bewustzijn en de betrokkenheid bij het prachtige eiland Cura\u00e7ao. Deze boeiende roadshow had een gedenkwaardig, leuk en kunstzinnig concept dat een onuitwisbare indruk achterliet op alle aanwezigen. De Cura\u00e7ao Roadshow was ontworpen om reisbureaus in Noord-Duitsland een meeslepende ervaring te bieden.<\/p>\n<p>Het hoogtepunt van de avond was een artistieke ervaring. Reisbureaus werden uitgenodigd om hun creatieve geest de vrije loop te laten door hun eigen Cura\u00e7aose straatkunstwerk te schilderen, waarbij elk kunstwerk uit 15 afzonderlijke doeken bestond. G\u00f6tz Friedewald, een professionele Duitse kunstenaar, was aanwezig om begeleiding te bieden en schildertechnieken te delen, zodat elk meesterwerk een waarheidsgetrouwe weerspiegeling was van de verbeelding van de kunstenaar. In elke stad (D\u00fcsseldorf, Bremen en Hamburg) werd het meesterwerk weggegeven aan \u00e9\u00e9n reisbureau dat het schilderij nu gebruikt als etalagedecoratie.<\/p>\n<p>In Berlijn werd er een speciaal tintje aan toegevoegd toen reisbureaus een Chichi schilderden. Deze keuze vond goede weerklank in Berlijn, waar Serena Israel is geboren en opgegroeid.<\/p>\n<p>Met in totaal 160 deelnemende reisbureaus verspreid over de vier steden bleek de Cura\u00e7ao Roadshow Duitsland een doorslaand succes. Deze creatieve roadshow volgt een traditie van innovatieve concepten, met eerdere edities met yoga op mini SUP-boards in 2018 en filmische presentaties van Cura\u00e7ao in 2019. Een reisagent uit D\u00fcsseldorf uitte zijn enthousiasme en zei: &#8220;Dit was het leukste evenement in D\u00fcsseldorf over twintig jaar!&#8221;<\/p>\n<p>De Cura\u00e7ao Roadshow Duitsland, gepresenteerd door CTBE en KLM Duitsland, slaagde erin een onuitwisbare indruk achter te laten op reisagenten en diepere verbindingen te smeden met Cura\u00e7ao en zijn levendige cultuur. Wij hopen veel van hun klanten te ontmoeten op ons prachtige eiland!<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/chichi-curacao.com\/wp-content\/uploads\/sites\/15\/2023\/10\/20230921_213225-scaled-e1696253613782.jpg&#8221; title_text=&#8221;20230921_213225&#8243; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_post_nav in_same_term=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; hide_prev=&#8221;off&#8221; hide_next=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_nav][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/chichi-curacao.com\/wp-content\/uploads\/sites\/15\/2023\/10\/WhatsApp-Image-2023-09-22-at-05.50.16-3.jpeg&#8221; title_text=&#8221;WhatsApp Image 2023-09-22 at 05.50.16 (3)&#8221; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/chichi-curacao.com\/wp-content\/uploads\/sites\/15\/2023\/10\/20230921_203450-scaled.jpg&#8221; title_text=&#8221;20230921_203450&#8243; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/chichi-curacao.com\/wp-content\/uploads\/sites\/15\/2023\/10\/20230921_212743-scaled.jpg&#8221; title_text=&#8221;20230921_212743&#8243; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Een creatieve odyssee om het bewustzijn te bevorderen<\/p>\n","protected":false},"author":144,"featured_media":18365,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p><img src=\"http:\/\/www.chichi-curacao.com\/graphic.php?table_name=news&field_name=foto&id=94\" alt=\"\" width=\"200\" align=\"left\" border=\"0\" hspace=\"7\" vspace=\"3\" \/><\/p><p>Das Erbe unserer Welt [Heritage of our World]. is in the special edition of the National Geographic magazine \u2013 in the German version -\u2018Das Erbe unserer Welt\u2019 [Heritage of our World]. An arts and cultural heritage magazine. \u2018Art of the Dutch Caribbean Islands\u2019. Serena chose a Shawawa-Chichi\u00ae to present her work on page 96. Check it out on the digital version.<\/p><p><a href=\"http:\/\/daserbeunsererwelt.com\/spring2015\/#page\/97\" target=\"_blank\">To the web version of the article<\/a><\/p><p><a href=\"http:\/\/www.chichi-curacao.com\/file\/das_erbe_unserer_welt.pdf\">Download article<\/a><\/p><p>\u00a0<\/p>","_et_gb_content_width":"","wds_primary_category":0,"footnotes":""},"categories":[33],"tags":[],"class_list":["post-18363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-nl"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:34:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/chichi-curacao.com\/nl\/wp-json\/wp\/v2\/posts\/18363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chichi-curacao.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chichi-curacao.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chichi-curacao.com\/nl\/wp-json\/wp\/v2\/users\/144"}],"replies":[{"embeddable":true,"href":"https:\/\/chichi-curacao.com\/nl\/wp-json\/wp\/v2\/comments?post=18363"}],"version-history":[{"count":0,"href":"https:\/\/chichi-curacao.com\/nl\/wp-json\/wp\/v2\/posts\/18363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chichi-curacao.com\/nl\/wp-json\/wp\/v2\/media\/18365"}],"wp:attachment":[{"href":"https:\/\/chichi-curacao.com\/nl\/wp-json\/wp\/v2\/media?parent=18363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chichi-curacao.com\/nl\/wp-json\/wp\/v2\/categories?post=18363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chichi-curacao.com\/nl\/wp-json\/wp\/v2\/tags?post=18363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}